{"id":14087,"date":"2022-05-24T13:58:05","date_gmt":"2022-05-24T13:58:05","guid":{"rendered":"https:\/\/carolinacat.com\/construction\/?page_id=14087"},"modified":"2025-07-30T17:21:51","modified_gmt":"2025-07-30T17:21:51","slug":"paving","status":"publish","type":"page","link":"https:\/\/carolinacat.com\/construction\/es\/new\/industries\/paving\/","title":{"rendered":"Paving"},"content":{"rendered":"\r\n<h1>Pavimentaci\u00f3n<\/h1>\r\n<h2>C\u00f3mo le servimos<\/h2>\r\n<p>\u00bfSus proyectos requieren la pavimentaci\u00f3n de obras, carreteras, aparcamientos, calzadas o pistas de aeropuertos? \u00bfHa llegado el momento de actualizar sus equipos o ampliar su flota?<\/p>\r\n<p>Si usted hace negocios en el oeste de Carolina del Norte, la<a href=\"https:\/\/carolinacat.com\/construction\/es\/locations\/\"> ubicaci\u00f3n m\u00e1s cercana de Carolina Cat<\/a> tiene todo lo que necesita para sus trabajos de pavimentaci\u00f3n. Hemos sido un proveedor de soluciones de equipos pesados de confianza en la regi\u00f3n desde 1926. As\u00f3ciese con nosotros para obtener un producto de alta calidad que cumpla con sus expectativas y un servicio excepcional para maximizar su experiencia.<\/p>\r\n<p>En Carolina Cat, nos asociamos con nuestros clientes para ayudarles a alcanzar sus objetivos empresariales y de proyecto.<\/p>\r\n<p><a href=\"https:\/\/carolinacat.com\/construction\/es\/contact-us\/\">Cont\u00e1ctenos<\/a><\/p>\r\n<p><img decoding=\"async\" title=\"undercarriage\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/undercarriage.jpg\" alt=\"persona con el tren de aterrizaje del equipo\" \/> <a href=\"https:\/\/carolinacat.com\/construction\/es\/new\/\" target=\"_self\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/helmet-icon.png\" \/><\/a><\/p>\r\n<h4>Tienda Nueva<\/h4>\r\n<p><a href=\"https:\/\/carolinacat.com\/construction\/es\/used-equipment\/\" target=\"_self\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/helmet-icon.png\" \/><\/a><\/p>\r\n<h4>Tienda de segunda mano<\/h4>\r\n<p><a href=\"https:\/\/carolinacat.com\/construction\/es\/rental\/\" target=\"_self\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/helmet-icon.png\" \/><\/a><\/p>\r\n<h4>Alquiler de equipos<\/h4>\r\n<p><a href=\"https:\/\/carolinacat.com\/construction\/es\/parts\/\" target=\"_self\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/helmet-icon.png\" \/><\/a><\/p>\r\n<h4>Tienda de piezas de recambio<\/h4>\r\n<p><a href=\"https:\/\/carolinacat.com\/construction\/es\/service\/\" target=\"_self\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/helmet-icon.png\" \/><\/a><\/p>\r\n<h4>Solicitar servicio<\/h4>\r\n<p><a href=\"https:\/\/parts.cat.com\/en\/carolinacat\" target=\"_self\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/helmet-icon.png\" \/><\/a><\/p>\r\n<h4>Pedir piezas<\/h4>\r\n<p>Utilice las flechas para ver m\u00e1s opciones<\/p>\r\n<h2>Piezas y servicios<\/h2>\r\n<p>Carolina Cat proporciona piezas f\u00e1cilmente disponibles y servicio experto. Encontrar\u00e1 una amplia selecci\u00f3n de piezas de repuesto Cat a la venta en <a href=\"https:\/\/parts.cat.com\/en\/carolinacat\" target=\"_blank\" rel=\"noopener noreferrer\">Parts.Cat.Com<\/a>. Busque y haga pedidos las 24 horas del d\u00eda desde su oficina, en el lugar de trabajo o sobre la marcha. Obtendr\u00e1 una entrega r\u00e1pida para mantener sus proyectos seg\u00fan lo previsto. Tambi\u00e9n puede comprar piezas en la tienda o por tel\u00e9fono.<\/p>\r\n<p>El servicio regular de equipos de pavimentaci\u00f3n de Carolina Cat mantendr\u00e1 su flota en el trabajo y funcionando sin problemas. A trav\u00e9s del mantenimiento planificado, podemos detectar problemas mec\u00e1nicos menores y corregirlos. Tambi\u00e9n podemos realizar todo tipo de reparaciones de forma r\u00e1pida y eficiente para minimizar el tiempo de inactividad improductivo.<\/p>\r\n<h2>Equipos nuevos y usados<\/h2>\r\n<p>Carolina Cat ayuda a su negocio a tener \u00e9xito todos los d\u00edas, asegur\u00e1ndose de que tiene la m\u00e1quina adecuada para el trabajo. Si usted est\u00e1 en el mercado de nuevos equipos de pavimentaci\u00f3n, tenemos los \u00faltimos modelos de Caterpillar, un l\u00edder en la industria durante casi un siglo. Los productos Cat\u00ae rinden en condiciones dif\u00edciles y ofrecen muchos a\u00f1os de servicio fiable.<\/p>\r\n<h2>Alquiler de material<\/h2>\r\n<p>Cualquiera que sea su necesidad, cualquiera que sea su industria, Carolina Cat tiene una l\u00ednea completa de equipos de alquiler para servirle. Nuestros especialistas en alquiler de equipos pueden ayudarle a explorar todas las opciones disponibles y tomar la mejor decisi\u00f3n para su negocio. Obtendr\u00e1 un producto bien mantenido y minuciosamente inspeccionado en el que puede confiar. Estableceremos un programa de alquiler diario, semanal o a largo plazo que se ajuste a sus necesidades y presupuesto.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><a href=\"https:\/\/carolinacat.com\/construction\/es\/find-a-rep\/\">Buscar un representante<\/a><\/p>\r\n<p><a href=\"https:\/\/carolinacat.com\/construction\/es\/rental-equipment\/machines\/compact-track-loaders\/\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/ctl-image.jpg\" alt=\"ctl-imagen.jpg\" \/> Cargadoras compactas de orugas <\/a> <a href=\"https:\/\/carolinacat.com\/construction\/es\/rental-equipment\/machines\/asphalt-pavers\/\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2022\/06\/Screenshot-2022-06-15-120958.jpg\" alt=\"Screenshot-2022-06-15-120958.jpg\" \/> Pavimentadoras de asfalto <\/a> <a href=\"https:\/\/carolinacat.com\/construction\/es\/rental-equipment\/machines\/backhoe-loaders\/\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2020\/04\/Backhoe-Loader.png\" alt=\"Retroexcavadora.png\" \/> Retroexcavadoras <\/a> <a href=\"https:\/\/carolinacat.com\/construction\/es\/rental-equipment\/machines\/excavators\/\"> <img decoding=\"async\" src=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2022\/06\/Screenshot-2022-06-15-121345.jpg\" alt=\"Screenshot-2022-06-15-121345.jpg\" \/> Excavadoras <\/a><\/p>\r\n<p>Utilice las flechas para ver m\u00e1s opciones<\/p>\r\n<h3>Nuestros afiliados<\/h3>\r\n<p>Conocemos el sector de la pavimentaci\u00f3n y los retos a los que se enfrenta a diario. Nuestro trabajo es ayudarle a hacer su trabajo de forma m\u00e1s eficiente y rentable. Tambi\u00e9n somos miembros orgullosos de:<\/p>\r\n<ul>\r\n<li><a href=\"http:\/\/www.apwa.net\/\" target=\"_blank\" rel=\"noopener\">Asociaci\u00f3n Americana de Obras P\u00fablicas<\/a><\/li>\r\n<li><a href=\"http:\/\/www.carolinaasphalt.org\/aws\/CAPA\/pt\/sp\/home_page\" target=\"_blank\" rel=\"noopener\">Asociaci\u00f3n de Pavimentos de Asfalto de Carolina<\/a><\/li>\r\n<\/ul>\r\n<h3><strong>Nuestra asociaci\u00f3n con Etnyre<\/strong><\/h3>\r\n<p>Carolina Cat se enorgullece de ofrecer a los clientes equipos, piezas y servicio para los productos Etnyre desde nuestra red de 10 ubicaciones. Etnyre es uno de nuestros socios de confianza y el l\u00edder del mercado de distribuidores de asfalto y esparcidores de gravilla en Am\u00e9rica del Norte.<\/p>\r\n<p>Para ventas, piezas, servicio, y soluciones completas del equipo, haga Carolina Cat su distribuidor exclusivo del equipo de pavimentaci\u00f3n para el equipo de Etnyre en Charlotte, Asheville, Greensboro y m\u00e1s all\u00e1. <a href=\"https:\/\/carolinacat.com\/construction\/es\/locations\/\">Encuentre una ubicaci\u00f3n<\/a> cerca de usted para empezar hoy.<\/p>\r\n<h2>Acuda a Carolina Cat para sus necesidades de equipos agr\u00edcolas<\/h2>\r\n<p>Desde 1926, hemos estado sirviendo a los trabajadores de la industria de pavimentaci\u00f3n de Carolina del Norte para que puedan mantener sus operaciones funcionando sin problemas y eficientemente. En la actualidad, seguimos cumpliendo nuestro compromiso de proporcionar equipos Cat fiables para cada trabajo. Sea lo que sea lo que necesite para su trabajo, d\u00e9jenos ayudarle a equiparse para hacerlo lo mejor posible. Para obtener m\u00e1s informaci\u00f3n sobre lo que podemos ofrecerle, p\u00f3ngase en contacto con nosotros hoy mismo.<br \/><a href=\"#\">P\u00f3ngase en contacto con nosotros hoy mismo<\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Pavimentaci\u00f3n C\u00f3mo le servimos \u00bfSus proyectos requieren pavimentaci\u00f3n para obras, carreteras, aparcamientos, entradas de veh\u00edculos o pistas de aeropuertos? \u00bfHa llegado el momento de actualizar su equipo o ampliar su flota? Si usted hace negocios en el oeste de Carolina del Norte, la ubicaci\u00f3n m\u00e1s cercana de Carolina Cat tiene todo lo que usted necesita para sus trabajos de pavimentaci\u00f3n. Hemos estado [...]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":108,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"class_list":["post-14087","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"\n<title>Pavimentaci\u00f3n - Carolina Cat Construction<\/title>\n<meta name=\"description\" content=\"Obtenga equipos de pavimentaci\u00f3n de primer nivel y soporte de Carolina Cat. Explore las nuevas pavimentadoras de asfalto, excavadoras y cargadoras compactas sobre orugas para sus necesidades de pavimentaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carolinacat.com\/construction\/es\/new\/industries\/paving\/\" \/>\n<meta property=\"og:locale\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pavimentaci\u00f3n - Carolina Cat Construction\" \/>\n<meta property=\"og:description\" content=\"Obtenga equipos de pavimentaci\u00f3n de primer nivel y soporte de Carolina Cat. Explore las nuevas pavimentadoras de asfalto, excavadoras y cargadoras compactas sobre orugas para sus necesidades de pavimentaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carolinacat.com\/construction\/es\/new\/industries\/paving\/\" \/>\n<meta property=\"og:site_name\" content=\"Carolina Cat Construction\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/carolinacat\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T17:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/undercarriage.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CarolinaCat\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/\",\"url\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/\",\"name\":\"Paving - Carolina Cat Construction\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/carolinacat.com\\\/content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/undercarriage.jpg\",\"datePublished\":\"2022-05-24T13:58:05+00:00\",\"dateModified\":\"2025-07-30T17:21:51+00:00\",\"description\":\"Get top-tier paving equipment and support from Carolina Cat. Explore new asphalt pavers, excavators and compact track loaders for your paving needs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/#primaryimage\",\"url\":\"https:\\\/\\\/carolinacat.com\\\/content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/undercarriage.jpg\",\"contentUrl\":\"https:\\\/\\\/carolinacat.com\\\/content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/undercarriage.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/new\\\/industries\\\/paving\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home | Construction\",\"item\":\"\\\/construction\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New\",\"item\":\"\\\/construction\\\/es\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Industries\",\"item\":\"\\\/construction\\\/es\\\/new\\\/industries\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Paving\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/#website\",\"url\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/\",\"name\":\"Carolina Cat Construction\",\"description\":\"Carolina Cat site\",\"publisher\":{\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/#organization\",\"name\":\"Carolina Cat\",\"url\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/carolinacat.com\\\/content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/Carolina_Cat_logo_stroke_HighRes.png\",\"contentUrl\":\"https:\\\/\\\/carolinacat.com\\\/content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/Carolina_Cat_logo_stroke_HighRes.png\",\"width\":1856,\"height\":494,\"caption\":\"Carolina Cat\"},\"image\":{\"@id\":\"https:\\\/\\\/carolinacat.com\\\/construction\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carolinacat\\\/\",\"https:\\\/\\\/x.com\\\/CarolinaCat\",\"https:\\\/\\\/www.instagram.com\\\/carolinacat\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/carolina-cat\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CarolinaCaterpillar\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paving - Carolina Cat Construction","description":"Obtenga equipos de pavimentaci\u00f3n de primer nivel y soporte de Carolina Cat. Explore las nuevas pavimentadoras de asfalto, excavadoras y cargadoras compactas sobre orugas para sus necesidades de pavimentaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/","og_locale":"en_US","og_type":"article","og_title":"Paving - Carolina Cat Construction","og_description":"Get top-tier paving equipment and support from Carolina Cat. Explore new asphalt pavers, excavators and compact track loaders for your paving needs.","og_url":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/","og_site_name":"Carolina Cat Construction","article_publisher":"https:\/\/www.facebook.com\/carolinacat\/","article_modified_time":"2025-07-30T17:21:51+00:00","og_image":[{"url":"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/undercarriage.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@CarolinaCat","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/","url":"https:\/\/carolinacat.com\/construction\/es\/new\/industries\/paving\/","name":"Pavimentaci\u00f3n - Carolina Cat Construction","isPartOf":{"@id":"https:\/\/carolinacat.com\/construction\/#website"},"primaryImageOfPage":{"@id":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/#primaryimage"},"image":{"@id":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/#primaryimage"},"thumbnailUrl":"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/undercarriage.jpg","datePublished":"2022-05-24T13:58:05+00:00","dateModified":"2025-07-30T17:21:51+00:00","description":"Obtenga equipos de pavimentaci\u00f3n de primer nivel y soporte de Carolina Cat. Explore las nuevas pavimentadoras de asfalto, excavadoras y cargadoras compactas sobre orugas para sus necesidades de pavimentaci\u00f3n.","breadcrumb":{"@id":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/#primaryimage","url":"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/undercarriage.jpg","contentUrl":"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2021\/04\/undercarriage.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/carolinacat.com\/construction\/new\/industries\/paving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio | Construcci\u00f3n","item":"\/construction\/es\/"},{"@type":"ListItem","position":2,"name":"Nuevo","item":"\/construction\/es\/new\/"},{"@type":"ListItem","position":3,"name":"Industrias","item":"\/construction\/es\/new\/industries\/"},{"@type":"ListItem","position":4,"name":"Pavimentaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/carolinacat.com\/construction\/#website","url":"https:\/\/carolinacat.com\/construction\/es\/","name":"Carolina Cat Construction","description":"P\u00e1gina web de Carolina Cat","publisher":{"@id":"https:\/\/carolinacat.com\/construction\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carolinacat.com\/construction\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/carolinacat.com\/construction\/#organization","name":"Cat de Carolina","url":"https:\/\/carolinacat.com\/construction\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/carolinacat.com\/construction\/#\/schema\/logo\/image\/","url":"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2019\/12\/Carolina_Cat_logo_stroke_HighRes.png","contentUrl":"https:\/\/carolinacat.com\/content\/uploads\/sites\/2\/2019\/12\/Carolina_Cat_logo_stroke_HighRes.png","width":1856,"height":494,"caption":"Carolina Cat"},"image":{"@id":"https:\/\/carolinacat.com\/construction\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/carolinacat\/","https:\/\/x.com\/CarolinaCat","https:\/\/www.instagram.com\/carolinacat\/","https:\/\/www.linkedin.com\/company\/carolina-cat\/","https:\/\/www.youtube.com\/user\/CarolinaCaterpillar\/"]}]}},"_links":{"self":[{"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/pages\/14087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/comments?post=14087"}],"version-history":[{"count":2,"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/pages\/14087\/revisions"}],"predecessor-version":[{"id":20926,"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/pages\/14087\/revisions\/20926"}],"up":[{"embeddable":true,"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/pages\/108"}],"wp:attachment":[{"href":"https:\/\/carolinacat.com\/construction\/wp-json\/wp\/v2\/media?parent=14087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}